{"id":44234,"date":"2025-03-12T16:24:25","date_gmt":"2025-03-12T15:24:25","guid":{"rendered":"https:\/\/figueras.com\/?p=44234"},"modified":"2025-03-12T16:24:25","modified_gmt":"2025-03-12T15:24:25","slug":"figueras-en-radio-3-asi-se-crea-la-butaca-perfecta","status":"publish","type":"post","link":"https:\/\/figueras.com\/es\/figueras-en-radio-3-asi-se-crea-la-butaca-perfecta\/","title":{"rendered":"Figueras en Radio 3: As\u00ed se crea la butaca perfecta"},"content":{"rendered":"<p><span data-contrast=\"auto\">En Figueras Seating, llevamos casi un siglo dise\u00f1ando y fabricando butacas que marcan la diferencia en auditorios, teatros, cines y estadios de todo el mundo. Pero, \u00bfqu\u00e9 hay detr\u00e1s del proceso de creaci\u00f3n de la butaca perfecta?<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Nuestro Director de Operaciones, <\/span><b><span data-contrast=\"auto\">Israel Nadal<\/span><\/b><span data-contrast=\"auto\">, y nuestra Directora de Marketing, <\/span><b><span data-contrast=\"auto\">Sandra Sancho<\/span><\/b><span data-contrast=\"auto\">, fueron entrevistados en el programa <\/span><i><span data-contrast=\"auto\">Hoy empieza todo 2<\/span><\/i><span data-contrast=\"auto\"> de <\/span><b><span data-contrast=\"auto\">Radio 3 -RNE<\/span><\/b><span data-contrast=\"auto\">. En la secci\u00f3n <\/span><i><span data-contrast=\"auto\">Manos Sucias<\/span><\/i><span data-contrast=\"auto\">, el periodista Nacho \u00c1lvaro convers\u00f3 con ellos sobre la trayectoria de Figueras, la transformaci\u00f3n del sector, el equilibrio entre dise\u00f1o, innovaci\u00f3n y funcionalidad, la tendencia en la diversificaci\u00f3n del uso en los espacios, las normativas y algunos de nuestros proyectos m\u00e1s ic\u00f3nicos.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Desde la investigaci\u00f3n ergon\u00f3mica hasta la selecci\u00f3n de materiales sostenibles, pasando por la precisi\u00f3n en cada detalle de fabricaci\u00f3n y nuestra capacidad de adaptaci\u00f3n a proyectos singulares, la entrevista ofrece una visi\u00f3n en profundidad sobre c\u00f3mo creamos asientos que elevan la experiencia del p\u00fablico y cumplen con los m\u00e1s altos est\u00e1ndares de calidad.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\ud83d\udd0a<\/span> <b><span data-contrast=\"auto\"><a href=\"https:\/\/www.rtve.es\/play\/audios\/hoy-empieza-todo-2\/hoy-empieza-todo-2-manos-sucias-figueras-seating-10-03-2025\/16484340\/\" target=\"_blank\" rel=\"noopener\">Esc\u00fachalo aqu\u00ed<\/a> <span class=\"TextRun SCXW126457554 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW126457554 BCX0\">o mira <a href=\"https:\/\/vimeo.com\/1064635053\" target=\"_blank\" rel=\"noopener\">la entrevista en este v\u00eddeo<\/a><\/span><\/span><\/span><\/b><\/p>\n<figure id=\"attachment_44235\" aria-describedby=\"caption-attachment-44235\" style=\"width: 768px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-44235\" title=\"Isra Sandra RNE Entrevista\" src=\"https:\/\/figueras.com\/wp-content\/uploads\/2025\/03\/Isra-Sandra-RNE-Entrevista-768x416.jpg\" alt=\"Isra Sandra RNE Entrevista\" width=\"768\" height=\"416\" srcset=\"https:\/\/figueras.com\/wp-content\/uploads\/2025\/03\/Isra-Sandra-RNE-Entrevista-768x416.jpg 768w, https:\/\/figueras.com\/wp-content\/uploads\/2025\/03\/Isra-Sandra-RNE-Entrevista-1024x555.jpg 1024w, https:\/\/figueras.com\/wp-content\/uploads\/2025\/03\/Isra-Sandra-RNE-Entrevista-480x260.jpg 480w, https:\/\/figueras.com\/wp-content\/uploads\/2025\/03\/Isra-Sandra-RNE-Entrevista.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption id=\"caption-attachment-44235\" class=\"wp-caption-text\">Isra Sandra RNE Entrevista<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En Figueras Seating, llevamos casi un siglo dise\u00f1ando y fabricando butacas que marcan la diferencia en auditorios, teatros, cines y estadios de todo el mundo. Pero, \u00bfqu\u00e9 hay detr\u00e1s del proceso de creaci\u00f3n de la butaca perfecta?\u00a0 Nuestro Director de Operaciones, Israel Nadal, y nuestra Directora de Marketing, Sandra Sancho, fueron entrevistados en el programa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":44238,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[274],"tags":[],"class_list":["post-44234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/figueras.com\/es\/wp-json\/wp\/v2\/posts\/44234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/figueras.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/figueras.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/figueras.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/figueras.com\/es\/wp-json\/wp\/v2\/comments?post=44234"}],"version-history":[{"count":0,"href":"https:\/\/figueras.com\/es\/wp-json\/wp\/v2\/posts\/44234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/figueras.com\/es\/wp-json\/wp\/v2\/media\/44238"}],"wp:attachment":[{"href":"https:\/\/figueras.com\/es\/wp-json\/wp\/v2\/media?parent=44234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/figueras.com\/es\/wp-json\/wp\/v2\/categories?post=44234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/figueras.com\/es\/wp-json\/wp\/v2\/tags?post=44234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}